{"id":10775,"date":"2022-08-25T13:49:16","date_gmt":"2022-08-25T17:49:16","guid":{"rendered":"https:\/\/viahr.org\/staging\/8024\/?p=10775"},"modified":"2022-08-25T13:49:17","modified_gmt":"2022-08-25T17:49:17","slug":"como-vivir-menos-estresado-en-el-dia-a-dia","status":"publish","type":"post","link":"https:\/\/viahr.org\/staging\/8024\/como-vivir-menos-estresado-en-el-dia-a-dia\/","title":{"rendered":"\u00bfC\u00f3mo vivir menos estresado en el d\u00eda a d\u00eda?\ufffc"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Si bien es important\u00edsimo responder a la pregunta <strong>\u00bfc\u00f3mo manejar el estr\u00e9s?<\/strong>, es igual -o m\u00e1s- importante responder<strong> \u00bfqu\u00e9 puedo hacer para estresarme menos?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el caso de la primera, es c\u00f3mo calmarnos una vez ya estamos estresados, en el caso de la segunda, es qu\u00e9 hacer para no tener que aplicar tanto la primera -aunque las situaciones sean las mismas, c\u00f3mo las interpreto con menos estr\u00e9s y m\u00e1s claridad-.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aprender a cambiar nuestra forma de percibir los eventos del d\u00eda a d\u00eda puede marcar la diferencia entre una vida ca\u00f3tica o una armoniosa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entonces, vamos a&nbsp; lo accionable.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La clave est\u00e1 en empezar a regularse ANTES de llegar al estr\u00e9s: El primer paso es reconocer: &#8220;Ok, estoy empezando a estresarme, \u00bfpor qu\u00e9?&#8221;&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Las preguntas siempre dan la ruta:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u00bfQu\u00e9 es LO PEOR que puede pasar si las cosas no salen como lo tengo en mente?<\/li><li>\u00bfEstoy proyectando mi tranquilidad en los resultados? \u00bfPuedo estar tranquilo aunque no todo salga como quiero?<\/li><li>\u00bfC\u00f3mo interpretar\u00eda esta misma situaci\u00f3n si no estuviese estresado?<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Esto es un ejercicio de &#8220;momento de estr\u00e9s a momento de estr\u00e9s&#8221;. Un escaneo r\u00e1pido de nuestros pensamientos y las preguntas correctas cambian c\u00f3mo vemos el evento.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo m\u00e1s importante es tener siempre en mente el m\u00e1gico <strong>&#8220;Puedo ver esta situaci\u00f3n sin estresarme. Puedo ver esta situaci\u00f3n sin miedo\/rabia\/angustia.&#8221;<\/strong> La ra\u00edz de la interpretaci\u00f3n est\u00e1 en nosotros, no en el evento.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si bien es important\u00edsimo responder a la pregunta \u00bfc\u00f3mo manejar el estr\u00e9s?, es igual -o m\u00e1s- importante responder \u00bfqu\u00e9 puedo hacer para estresarme menos? En el caso de la primera, es c\u00f3mo calmarnos una vez ya estamos estresados, en el caso de la segunda, es qu\u00e9 hacer para no tener que aplicar tanto la primera [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":10776,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"nf_dc_page":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[103,72],"tags":[235,237,236],"class_list":["post-10775","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aprender-a-hacer-pausas","category-burnout","tag-estresado","tag-estresarme-menos","tag-manejar-el-estres"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfC\u00f3mo vivir menos estresado en el d\u00eda a d\u00eda?\ufffc - VIAHR<\/title>\n<meta name=\"description\" content=\"Esto es un ejercicio de &quot;momento de estr\u00e9s a momento de estr\u00e9s&quot;. Un escaneo r\u00e1pido de nuestros pensamientos y las preguntas correctas cambian c\u00f3mo vemos el evento.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo vivir menos estresado en el d\u00eda a d\u00eda?\ufffc - VIAHR\" \/>\n<meta property=\"og:description\" content=\"Esto es un ejercicio de &quot;momento de estr\u00e9s a momento de estr\u00e9s&quot;. Un escaneo r\u00e1pido de nuestros pensamientos y las preguntas correctas cambian c\u00f3mo vemos el evento.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/viahr.org\/como-vivir-menos-estresado-en-el-dia-a-dia\/\" \/>\n<meta property=\"og:site_name\" content=\"VIAHR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/viahr.org\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-25T17:49:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-25T17:49:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/viahr.org\/wp-content\/uploads\/2022\/08\/\u00bfCo\u0301mo-vivir-menos-estresado-en-el-di\u0301a-a-dia.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Fernanda Prieto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fernanda Prieto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/viahr.org\\\/como-vivir-menos-estresado-en-el-dia-a-dia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/viahr.org\\\/como-vivir-menos-estresado-en-el-dia-a-dia\\\/\"},\"author\":{\"name\":\"Fernanda Prieto\",\"@id\":\"https:\\\/\\\/viahr.org\\\/staging\\\/8024\\\/#\\\/schema\\\/person\\\/f76c7eb2fa91e17d85bb6550ab14ebee\"},\"headline\":\"\u00bfC\u00f3mo vivir menos estresado en el d\u00eda a d\u00eda?\ufffc\",\"datePublished\":\"2022-08-25T17:49:16+00:00\",\"dateModified\":\"2022-08-25T17:49:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/viahr.org\\\/como-vivir-menos-estresado-en-el-dia-a-dia\\\/\"},\"wordCount\":277,\"publisher\":{\"@id\":\"https:\\\/\\\/viahr.org\\\/staging\\\/8024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/viahr.org\\\/como-vivir-menos-estresado-en-el-dia-a-dia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/viahr.org\\\/staging\\\/8024\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/\u00bfCo\u0301mo-vivir-menos-estresado-en-el-di\u0301a-a-dia.png\",\"keywords\":[\"estresado\",\"estresarme menos\",\"manejar el estr\u00e9s\"],\"articleSection\":[\"Aprender a hacer pausas\",\"Burnout\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/viahr.org\\\/como-vivir-menos-estresado-en-el-dia-a-dia\\\/\",\"url\":\"https:\\\/\\\/viahr.org\\\/como-vivir-menos-estresado-en-el-dia-a-dia\\\/\",\"name\":\"\u00bfC\u00f3mo vivir menos estresado en el d\u00eda a d\u00eda?\ufffc - VIAHR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/viahr.org\\\/staging\\\/8024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/viahr.org\\\/como-vivir-menos-estresado-en-el-dia-a-dia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/viahr.org\\\/como-vivir-menos-estresado-en-el-dia-a-dia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/viahr.org\\\/staging\\\/8024\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/\u00bfCo\u0301mo-vivir-menos-estresado-en-el-di\u0301a-a-dia.png\",\"datePublished\":\"2022-08-25T17:49:16+00:00\",\"dateModified\":\"2022-08-25T17:49:17+00:00\",\"description\":\"Esto es un ejercicio de \\\"momento de estr\u00e9s a momento de estr\u00e9s\\\". Un escaneo r\u00e1pido de nuestros pensamientos y las preguntas correctas cambian c\u00f3mo vemos el evento.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/viahr.org\\\/como-vivir-menos-estresado-en-el-dia-a-dia\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/viahr.org\\\/como-vivir-menos-estresado-en-el-dia-a-dia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/viahr.org\\\/como-vivir-menos-estresado-en-el-dia-a-dia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/viahr.org\\\/staging\\\/8024\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/\u00bfCo\u0301mo-vivir-menos-estresado-en-el-di\u0301a-a-dia.png\",\"contentUrl\":\"https:\\\/\\\/viahr.org\\\/staging\\\/8024\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/\u00bfCo\u0301mo-vivir-menos-estresado-en-el-di\u0301a-a-dia.png\",\"width\":1200,\"height\":800,\"caption\":\"\u00bfCo\u0301mo-vivir-menos-estresado-en-el-di\u0301a-a-dia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/viahr.org\\\/como-vivir-menos-estresado-en-el-dia-a-dia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/viahr.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfC\u00f3mo vivir menos estresado en el d\u00eda a d\u00eda?\ufffc\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/viahr.org\\\/staging\\\/8024\\\/#website\",\"url\":\"https:\\\/\\\/viahr.org\\\/staging\\\/8024\\\/\",\"name\":\"VIAHR\",\"description\":\"Vacation is a human right\",\"publisher\":{\"@id\":\"https:\\\/\\\/viahr.org\\\/staging\\\/8024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/viahr.org\\\/staging\\\/8024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/viahr.org\\\/staging\\\/8024\\\/#organization\",\"name\":\"VIAHR\",\"alternateName\":\"VIAHR FOUNDATION\",\"url\":\"https:\\\/\\\/viahr.org\\\/staging\\\/8024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/viahr.org\\\/staging\\\/8024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/viahr.org\\\/staging\\\/8024\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logotipo-Viahr-Foundation.png\",\"contentUrl\":\"https:\\\/\\\/viahr.org\\\/staging\\\/8024\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logotipo-Viahr-Foundation.png\",\"width\":320,\"height\":320,\"caption\":\"VIAHR\"},\"image\":{\"@id\":\"https:\\\/\\\/viahr.org\\\/staging\\\/8024\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/viahr.org\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/viahr.org\\\/staging\\\/8024\\\/#\\\/schema\\\/person\\\/f76c7eb2fa91e17d85bb6550ab14ebee\",\"name\":\"Fernanda Prieto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71a59b6c589b88e6162a5dcc300abad59db23afd695cf661fbf6e9487ab64ab3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71a59b6c589b88e6162a5dcc300abad59db23afd695cf661fbf6e9487ab64ab3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71a59b6c589b88e6162a5dcc300abad59db23afd695cf661fbf6e9487ab64ab3?s=96&d=mm&r=g\",\"caption\":\"Fernanda Prieto\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo vivir menos estresado en el d\u00eda a d\u00eda?\ufffc - VIAHR","description":"Esto es un ejercicio de \"momento de estr\u00e9s a momento de estr\u00e9s\". Un escaneo r\u00e1pido de nuestros pensamientos y las preguntas correctas cambian c\u00f3mo vemos el evento.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"\u00bfC\u00f3mo vivir menos estresado en el d\u00eda a d\u00eda?\ufffc - VIAHR","og_description":"Esto es un ejercicio de \"momento de estr\u00e9s a momento de estr\u00e9s\". Un escaneo r\u00e1pido de nuestros pensamientos y las preguntas correctas cambian c\u00f3mo vemos el evento.","og_url":"https:\/\/viahr.org\/como-vivir-menos-estresado-en-el-dia-a-dia\/","og_site_name":"VIAHR","article_publisher":"https:\/\/www.facebook.com\/viahr.org","article_published_time":"2022-08-25T17:49:16+00:00","article_modified_time":"2022-08-25T17:49:17+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/viahr.org\/wp-content\/uploads\/2022\/08\/\u00bfCo\u0301mo-vivir-menos-estresado-en-el-di\u0301a-a-dia.png","type":"image\/png"}],"author":"Fernanda Prieto","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Fernanda Prieto","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/viahr.org\/como-vivir-menos-estresado-en-el-dia-a-dia\/#article","isPartOf":{"@id":"https:\/\/viahr.org\/como-vivir-menos-estresado-en-el-dia-a-dia\/"},"author":{"name":"Fernanda Prieto","@id":"https:\/\/viahr.org\/staging\/8024\/#\/schema\/person\/f76c7eb2fa91e17d85bb6550ab14ebee"},"headline":"\u00bfC\u00f3mo vivir menos estresado en el d\u00eda a d\u00eda?\ufffc","datePublished":"2022-08-25T17:49:16+00:00","dateModified":"2022-08-25T17:49:17+00:00","mainEntityOfPage":{"@id":"https:\/\/viahr.org\/como-vivir-menos-estresado-en-el-dia-a-dia\/"},"wordCount":277,"publisher":{"@id":"https:\/\/viahr.org\/staging\/8024\/#organization"},"image":{"@id":"https:\/\/viahr.org\/como-vivir-menos-estresado-en-el-dia-a-dia\/#primaryimage"},"thumbnailUrl":"https:\/\/viahr.org\/staging\/8024\/wp-content\/uploads\/2022\/08\/\u00bfCo\u0301mo-vivir-menos-estresado-en-el-di\u0301a-a-dia.png","keywords":["estresado","estresarme menos","manejar el estr\u00e9s"],"articleSection":["Aprender a hacer pausas","Burnout"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/viahr.org\/como-vivir-menos-estresado-en-el-dia-a-dia\/","url":"https:\/\/viahr.org\/como-vivir-menos-estresado-en-el-dia-a-dia\/","name":"\u00bfC\u00f3mo vivir menos estresado en el d\u00eda a d\u00eda?\ufffc - VIAHR","isPartOf":{"@id":"https:\/\/viahr.org\/staging\/8024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/viahr.org\/como-vivir-menos-estresado-en-el-dia-a-dia\/#primaryimage"},"image":{"@id":"https:\/\/viahr.org\/como-vivir-menos-estresado-en-el-dia-a-dia\/#primaryimage"},"thumbnailUrl":"https:\/\/viahr.org\/staging\/8024\/wp-content\/uploads\/2022\/08\/\u00bfCo\u0301mo-vivir-menos-estresado-en-el-di\u0301a-a-dia.png","datePublished":"2022-08-25T17:49:16+00:00","dateModified":"2022-08-25T17:49:17+00:00","description":"Esto es un ejercicio de \"momento de estr\u00e9s a momento de estr\u00e9s\". Un escaneo r\u00e1pido de nuestros pensamientos y las preguntas correctas cambian c\u00f3mo vemos el evento.","breadcrumb":{"@id":"https:\/\/viahr.org\/como-vivir-menos-estresado-en-el-dia-a-dia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/viahr.org\/como-vivir-menos-estresado-en-el-dia-a-dia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/viahr.org\/como-vivir-menos-estresado-en-el-dia-a-dia\/#primaryimage","url":"https:\/\/viahr.org\/staging\/8024\/wp-content\/uploads\/2022\/08\/\u00bfCo\u0301mo-vivir-menos-estresado-en-el-di\u0301a-a-dia.png","contentUrl":"https:\/\/viahr.org\/staging\/8024\/wp-content\/uploads\/2022\/08\/\u00bfCo\u0301mo-vivir-menos-estresado-en-el-di\u0301a-a-dia.png","width":1200,"height":800,"caption":"\u00bfCo\u0301mo-vivir-menos-estresado-en-el-di\u0301a-a-dia"},{"@type":"BreadcrumbList","@id":"https:\/\/viahr.org\/como-vivir-menos-estresado-en-el-dia-a-dia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/viahr.org\/"},{"@type":"ListItem","position":2,"name":"\u00bfC\u00f3mo vivir menos estresado en el d\u00eda a d\u00eda?\ufffc"}]},{"@type":"WebSite","@id":"https:\/\/viahr.org\/staging\/8024\/#website","url":"https:\/\/viahr.org\/staging\/8024\/","name":"VIAHR","description":"Vacation is a human right","publisher":{"@id":"https:\/\/viahr.org\/staging\/8024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/viahr.org\/staging\/8024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/viahr.org\/staging\/8024\/#organization","name":"VIAHR","alternateName":"VIAHR FOUNDATION","url":"https:\/\/viahr.org\/staging\/8024\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/viahr.org\/staging\/8024\/#\/schema\/logo\/image\/","url":"https:\/\/viahr.org\/staging\/8024\/wp-content\/uploads\/2022\/06\/logotipo-Viahr-Foundation.png","contentUrl":"https:\/\/viahr.org\/staging\/8024\/wp-content\/uploads\/2022\/06\/logotipo-Viahr-Foundation.png","width":320,"height":320,"caption":"VIAHR"},"image":{"@id":"https:\/\/viahr.org\/staging\/8024\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/viahr.org"]},{"@type":"Person","@id":"https:\/\/viahr.org\/staging\/8024\/#\/schema\/person\/f76c7eb2fa91e17d85bb6550ab14ebee","name":"Fernanda Prieto","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/71a59b6c589b88e6162a5dcc300abad59db23afd695cf661fbf6e9487ab64ab3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71a59b6c589b88e6162a5dcc300abad59db23afd695cf661fbf6e9487ab64ab3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71a59b6c589b88e6162a5dcc300abad59db23afd695cf661fbf6e9487ab64ab3?s=96&d=mm&r=g","caption":"Fernanda Prieto"}}]}},"_links":{"self":[{"href":"https:\/\/viahr.org\/staging\/8024\/wp-json\/wp\/v2\/posts\/10775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/viahr.org\/staging\/8024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/viahr.org\/staging\/8024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/viahr.org\/staging\/8024\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/viahr.org\/staging\/8024\/wp-json\/wp\/v2\/comments?post=10775"}],"version-history":[{"count":2,"href":"https:\/\/viahr.org\/staging\/8024\/wp-json\/wp\/v2\/posts\/10775\/revisions"}],"predecessor-version":[{"id":10778,"href":"https:\/\/viahr.org\/staging\/8024\/wp-json\/wp\/v2\/posts\/10775\/revisions\/10778"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/viahr.org\/staging\/8024\/wp-json\/wp\/v2\/media\/10776"}],"wp:attachment":[{"href":"https:\/\/viahr.org\/staging\/8024\/wp-json\/wp\/v2\/media?parent=10775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/viahr.org\/staging\/8024\/wp-json\/wp\/v2\/categories?post=10775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/viahr.org\/staging\/8024\/wp-json\/wp\/v2\/tags?post=10775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}